{"id":4679,"date":"2024-08-26T10:28:08","date_gmt":"2024-08-26T07:28:08","guid":{"rendered":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V.jpg"},"modified":"2024-08-26T10:28:08","modified_gmt":"2024-08-26T07:28:08","slug":"img-eee90762838a55b014ed89b9df0cdd29-v","status":"inherit","type":"attachment","link":"https:\/\/icsanaas.com.ua\/en\/%d1%80%d0%be%d0%b1%d0%be%d1%87%d0%b0-%d0%bf%d1%80%d0%be%d0%b3%d1%80%d0%b0%d0%bc%d0%b0-%d0%b2%d0%b8%d0%ba%d0%be%d0%bd%d0%b0%d0%bd%d0%bd%d1%8f-%d0%b7%d0%b0%d0%b2%d0%b4%d0%b0%d0%bd%d0%bd%d1%8f-43-00-01-0\/img-eee90762838a55b014ed89b9df0cdd29-v\/","title":{"rendered":"IMG-eee90762838a55b014ed89b9df0cdd29-V"},"author":2,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"_links_to":"","_links_to_target":""},"class_list":["post-4679","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-300x225.jpg 300w, https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-1024x768.jpg 1024w, https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-768x576.jpg 768w, https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-1536x1152.jpg 1536w, https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1200,"file":"2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V.jpg","filesize":243607,"sizes":{"medium":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-300x225.jpg","width":300,"height":225,"filesize":19987,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-300x225.jpg"},"large":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-1024x768.jpg","width":1024,"height":768,"filesize":176578,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-1024x768.jpg"},"thumbnail":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-150x150.jpg","width":150,"height":150,"filesize":7778,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-150x150.jpg"},"medium_large":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-768x576.jpg","width":768,"height":576,"filesize":104066,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-768x576.jpg"},"1536x1536":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-1536x1152.jpg","width":1536,"height":1152,"filesize":354789,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-1536x1152.jpg"},"bizberg_medium":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-300x300.jpg","width":300,"height":300,"filesize":25071,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-300x300.jpg"},"bizberg_gallery":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-500x400.jpg","width":500,"height":400,"filesize":49361,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-500x400.jpg"},"bizberg_blog_list":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-368x240.jpg","width":368,"height":240,"filesize":23869,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-368x240.jpg"},"bizberg_detail_image":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-825x400.jpg","width":825,"height":400,"filesize":75816,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-825x400.jpg"},"bizberg_portfolio_homepage":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-600x400.jpg","width":600,"height":400,"filesize":57933,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-600x400.jpg"},"bizberg_blog_list_no_sidebar_1":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-220x190.jpg","width":220,"height":190,"filesize":13111,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-220x190.jpg"},"bizberg_detail_image_no_sidebar":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V-920x400.jpg","width":920,"height":400,"filesize":82871,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V-920x400.jpg"},"full":{"file":"IMG-eee90762838a55b014ed89b9df0cdd29-V.jpg","width":1600,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":4673,"source_url":"https:\/\/icsanaas.com.ua\/wp-content\/uploads\/2024\/08\/IMG-eee90762838a55b014ed89b9df0cdd29-V.jpg","_links":{"self":[{"href":"https:\/\/icsanaas.com.ua\/en\/wp-json\/wp\/v2\/media\/4679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icsanaas.com.ua\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/icsanaas.com.ua\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/icsanaas.com.ua\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/icsanaas.com.ua\/en\/wp-json\/wp\/v2\/comments?post=4679"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":4673,"href":"https:\/\/icsanaas.com.ua\/en\/wp-json\/wp\/v2\/posts\/4673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}